{"id":644,"date":"2020-05-29T07:55:35","date_gmt":"2020-05-29T07:55:35","guid":{"rendered":"https:\/\/pastisseriafaixat.com\/condicions-del-servei\/"},"modified":"2025-11-28T08:03:23","modified_gmt":"2025-11-28T08:03:23","slug":"condiciones-del-servicio","status":"publish","type":"page","link":"https:\/\/pastisseriafaixat.com\/es\/condiciones-del-servicio\/","title":{"rendered":"Condiciones generales de venta"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"644\" class=\"elementor elementor-644 elementor-48\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c610cf elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"0c610cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2e6c39\" data-id=\"d2e6c39\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7fd1fd elementor-widget elementor-widget-text-editor\" data-id=\"f7fd1fd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><strong><u> INFORMACI\u00d3N GENERAL<\/u><\/strong><\/li><\/ol><p>La titularitat d&#8217;aquest lloc web, (d&#8217;ara endavant Lloc Web) l&#8217;ostenta:<\/p><p>Pastisseria Faixat S.L., tiene su domicilio social en calle Muntaner, 159-161, local, c\u00f3digo postal 08036 \u2013 Barcelona.<\/p><p>Se halla inscrita en el Registro Mercantil de Barcelona al Tomo 9409, Folio 154, hoja 80743, y su CIF es B-08434250<\/p><p>Si quiere ponerse en contacto con nosotros puede hacerlo llamando al tel\u00e9fono 934 30 53 14 o a trav\u00e9s del e-mail info@pastisseriafaixat.com<\/p><p>Este documento (as\u00ed como otros documentos que aqu\u00ed se mencionen) regula las condiciones por las que se rige el uso de este Sitio Web y la compra o adquisici\u00f3n de productos y\/o servicios en el mismo (en adelante, Condiciones).<\/p><p>A efectos de estas Condiciones se entiende que la actividad que se desarrolla a trav\u00e9s del Sitio Web comprende: venta minorista de productos de reposter\u00eda de la sociedad Pastisseria Faixat, S.L. relacionados en la p\u00e1gina web de dicha sociedad.<\/p><p>Adem\u00e1s de leer las presentes Condiciones, antes de acceder, navegar y\/o usar esta p\u00e1gina web, el Usuario ha de haber le\u00eddo el Aviso Legal y las Condiciones Generales de Uso, incluyendo, la pol\u00edtica de cookies, y la pol\u00edtica de privacidad y de protecci\u00f3n de datos.<\/p><p>Al utilizar este Sitio Web o al hacer y\/o solicitar la adquisici\u00f3n de un producto y\/o servicio a trav\u00e9s del mismo el Usuario consiente quedar vinculado por estas Condiciones y por todo lo anteriormente mencionado, por lo que, si no est\u00e1 de acuerdo con todo ello, no debe usar este Sitio Web.<\/p><p>Asimismo, se informa que estas Condiciones podr\u00edan ser modificadas. El Usuario es responsable de consultarlas cada vez que acceda, navegue y\/o use el Sitio Web ya que ser\u00e1n aplicables aquellas que se encuentren vigentes en el momento en que se solicite la adquisici\u00f3n de productos y\/o servicios. <\/p><p>Para todas las preguntas que el Usuario pueda tener en relaci\u00f3n con las Condiciones puede ponerse en contacto con el titular utilizando los datos de contacto facilitados m\u00e1s arriba o, en su caso, utilizando el formulario de contacto.<\/p><ol start=\"2\"><li><strong><u> EL USUARIO<\/u><\/strong><\/li><\/ol><p>El acceso, la navegaci\u00f3n y uso del Sitio Web, confiere la condici\u00f3n de usuario (en adelante referido, indistintamente, individualmente como Usuario o conjuntamente como Usuarios), por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso.<\/p><p>El Usuario asume su responsabilidad de un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a: <\/p><ul><li>Hacer uso de este Sitio Web \u00fanicamente para realizar consultas y compras o adquisiciones legalmente v\u00e1lidas.<\/li><li>No realizar ninguna compra falsa o fraudulenta. Si razonablemente se pudiera considerar que se ha hecho una compra de esta \u00edndole, podr\u00eda ser anulada y se informar\u00eda a las autoridades pertinentes. <\/li><li>Facilitar datos de contacto veraces y l\u00edcitos, por ejemplo, direcci\u00f3n de correo electr\u00f3nico, direcci\u00f3n postal y\/u otros datos (ver Aviso Legal y Condiciones Generales de Uso).<\/li><\/ul><p>El Usuario declara ser mayor de 18 a\u00f1os y tener capacidad legal para celebrar contratos a trav\u00e9s de este Sitio Web.<\/p><p>El Sitio Web est\u00e1 dirigido principalmente a Usuarios residentes en Espa\u00f1a. no asegura que el Sitio Web cumpla con legislaciones de otros pa\u00edses, ya sea total o parcialmente. declina toda responsabilidad que se pueda derivar de dicho acceso, as\u00ed como tampoco asegura env\u00edos o prestaci\u00f3n de servicios fuera de Espa\u00f1a.  <\/p><p>El Usuario podr\u00e1 formalizar, a su elecci\u00f3n, el contrato de compraventa de los productos y\/o servicios deseados en cualquiera de los idiomas en los que las presentes Condiciones est\u00e9n disponibles en este Sitio Web.<\/p><ol start=\"3\"><li><strong><u> PROCESO DE COMPRA O ADQUISICI\u00d3N<\/u><\/strong><\/li><\/ol><p>Los Usuarios pueden comprar en el Sitio Web por los medios y formas establecidos. Deber\u00e1n seguir el procedimiento de compra y\/o adquisici\u00f3n online de la presente p\u00e1gina Web durante el cual varios productos y\/o servicios pueden ser seleccionados y a\u00f1adidos al carrito, cesta o espacio final de compra y, finalmente, hacer clic en <a href=\"https:\/\/pastisseriafaixat.com\/es\/confirmar\/\">https:\/\/pastisseriafaixat.com\/es\/finalizar-compra <\/a> <\/p><p>Asimismo, el Usuario deber\u00e1 rellenar y\/o comprobar la informaci\u00f3n que en cada paso se le solicita, aunque, durante el proceso de compra, antes de realizar el pago, se pueden modificar los datos de la compra.<\/p><p>Seguidamente, el Usuario recibir\u00e1 un correo electr\u00f3nico confirmando que ha recibido su pedido o solicitud de compra y\/o prestaci\u00f3n del servicio, es decir, la confirmaci\u00f3n del pedido. Y, en su caso, se le informar\u00e1, igualmente, mediante correo electr\u00f3nico cuando su compra est\u00e9 siendo enviada. <\/p><p>Una vez el procedimiento de compra ha concluido, el Usuario consiente que el Sitio Web genere una factura electr\u00f3nica que se har\u00e1 llegar al Usuario a trav\u00e9s del correo electr\u00f3nico. Asimismo, el Usuario puede, si as\u00ed lo desea, obtener una copia de su factura en papel, solicit\u00e1ndolo y utilizando los espacios de contacto del Sitio Web o a trav\u00e9s de los datos de contacto facilitados m\u00e1s arriba. <\/p><p>El Usuario reconoce estar al corriente, en el momento de la compra, de ciertas condiciones particulares de venta que conciernen al producto y\/o servicio en cuesti\u00f3n y que se muestran junto a la presentaci\u00f3n o, en su caso, imagen de \u00e9ste en su p\u00e1gina del Sitio Web, indicando, a modo enunciativo, pero no exhaustivo, y atendiendo a cada caso: nombre, precio, componentes, peso, cantidad, color, detalles de los productos, o caracter\u00edsticas, modo en el que se llevar\u00e1n a cabo y\/o coste de las prestaciones; y reconoce que la realizaci\u00f3n del pedido de compra o adquisici\u00f3n materializa la aceptaci\u00f3n plena y completa de las condiciones particulares de venta aplicables a cada caso.<\/p><p>Las comunicaciones, \u00f3rdenes de compra y pagos que intervengan durante las transacciones efectuadas en el Sitio Web podr\u00edan ser archivadas y conservadas en los registros informatizados de con el fin de constituir un medio de prueba de las transacciones, en todo caso, respetando las condiciones razonables de seguridad y las leyes y normativas vigentes que a este respecto sean de aplicaci\u00f3n, y particularmente atendiendo al Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD) y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales, y a los derechos que asisten a los Usuarios conforme a la pol\u00edtica de privacidad de este Sitio Web.<\/p><ol start=\"4\"><li><strong><u> DISPONIBILIDAD<\/u><\/strong><\/li><\/ol><p>Todos los pedidos de compra recibidos a trav\u00e9s del Sitio Web est\u00e1n sujetos a la disponibilidad de los productos y\/o a que ninguna circunstancia o causa de fuerza mayor (cl\u00e1usula nueve de estas Condiciones) afecte al suministro de los mismos y\/o a la prestaci\u00f3n de los servicios. Si se produjeran dificultades en cuanto al suministro de productos o no quedaran productos en stock, se compromete a contactar al Usuario y reembolsar cualquier cantidad que pudiera haber sido abonada en concepto de importe. Esto ser\u00e1 igualmente aplicable en los casos en los que la prestaci\u00f3n de un servicio deviniera irrealizable.  <\/p><ol start=\"5\"><li><strong><u> PRECIOS Y PAGO<\/u><\/strong><\/li><\/ol><p>Los precios exhibidos en el Sitio Web son los finales, en euros (\u20ac) e incluyen los impuestos, salvo que, por exigencia legal, especialmente en lo relativo al IVA, se se\u00f1ale y aplique cuesti\u00f3n distinta.<\/p><p>Los gastos de env\u00edo se encuentran incluidos en los precios finales de los productos tal y como se muestran en el Sitio Web.<\/p><p>En ning\u00fan caso el Sitio Web a\u00f1adir\u00e1 costes adicionales al precio de un producto o de un servicio de forma autom\u00e1tica, sino solo aquellos que el Usuario haya seleccionado y elegido voluntaria y libremente.<\/p><p>Los precios pueden cambiar en cualquier momento, pero los posibles cambios no afectar\u00e1n a los pedidos o compras con respecto a los que el Usuario ya haya recibido una confirmaci\u00f3n de pedido.<\/p><p>Los medios de pago aceptados ser\u00e1n: Tarjeta de cr\u00e9dito o d\u00e9bito<\/p><p> <\/p><p>Las tarjetas de cr\u00e9dito estar\u00e1n sujetas a comprobaciones y autorizaciones por parte de la entidad bancaria emisora de las mismas, si dicha entidad no autorizase el pago, no ser\u00e1 responsable por ning\u00fan retraso o falta de entrega y no podr\u00e1 formalizar ning\u00fan contrato con el Usuario.<\/p><p>Una vez que se reciba la orden de compra por parte del Usuario a trav\u00e9s del Sitio Web, se har\u00e1 una pre-autorizaci\u00f3n en la tarjeta que corresponda para asegurar que existen fondos suficientes para completar la transacci\u00f3n. El cargo en la tarjeta se har\u00e1 en el momento en que se env\u00ede al Usuario la confirmaci\u00f3n de env\u00edo y\/o confirmaci\u00f3n del servicio que se presta en forma y, en su caso, lugares establecidos. <\/p><p>En todo caso, al hacer clic en el lugar indicado anteriormente el Usuario confirma que el m\u00e9todo de pago utilizado es suyo.<\/p><ol start=\"6\"><li><strong><u> ENTREGA<\/u><\/strong><\/li><\/ol><p>En los casos en los que proceda realizar la entrega f\u00edsica del bien contratado, las entregas se efectuar\u00e1n en el \u00e1mbito del siguiente territorio: Barcelona ciudad.<\/p><p>Exceptuando aquellos casos en los que existan circunstancias imprevistas o extraordinarias o, en su caso, derivadas de la personalizaci\u00f3n de los productos, el pedido de compra consistente en los productos relacionados en cada confirmaci\u00f3n de compra ser\u00e1 entregado en el plazo se\u00f1alado en el Sitio Web seg\u00fan el m\u00e9todo de env\u00edo seleccionado por el Usuario. y, en todo cas, como m\u00ednimo 2 dias despu\u00e9s de haber formalizado la venta.<\/p><p>Si por alg\u00fan motivo, que le fuera imputable, no pudiera cumplir con la fecha de entrega, contactar\u00e1 al Usuario para informarle de esta circunstancia y, \u00e9ste podr\u00e1 elegir seguir adelante con la compra estableciendo una nueva fecha de entrega o bien anular el pedido con el reembolso total del precio pagado. En cualquier caso, las entregas a domicilio se realizan en d\u00edas laborables entiendo por tales de lunes a viernes en horario comercial. El horario comercial es de lunes a s\u00e1bado de 8 a 21:00 horas. Domingos y festivos de 09:00 a 15:00 horas  <\/p><p>Si resultara imposible efectuar la entrega del pedido por ausencia del Usuario, el pedido podr\u00eda ser devuelto al almac\u00e9n. No obstante, el transportista dejar\u00eda un aviso explicando d\u00f3nde se encuentra el pedido y c\u00f3mo hacer para que sea entregado de nuevo. <\/p><p>Si el Usuario no va a estar en el lugar de entrega en la franja horaria convenida, debe ponerse en contacto para convenir la entrega otro d\u00eda.<\/p><p>En caso de que transcurran 30 d\u00edas desde que su pedido est\u00e9 disponible para su entrega, y no haya sido entregado por causa no imputable a Pastisseria Faixat, S.L. se entender\u00e1 que el Usuario desea desistir del contrato y \u00e9ste se considerar\u00e1 resuelto.<\/p><p>Como consecuencia de la resoluci\u00f3n del contrato y dado que se trata de productos perecederos todos los pagos recibidos del Usuario no le ser\u00e1n devueltos.<\/p><p>A efectos de las presentes Condiciones, se entender\u00e1 que se ha producido la entrega o que el pedido ha sido entregado en el momento en el que el Usuario o un tercero indicado por el Usuario adquiera la posesi\u00f3n material de los productos, lo que se acreditar\u00e1 mediante la firma de la recepci\u00f3n del pedido en la direcci\u00f3n de entrega convenida.<\/p><p>Los riesgos que de los productos se pudieran derivar ser\u00e1n a cargo del Usuario a partir del momento de su entrega. El Usuario adquiere la propiedad de los productos en el momento de la entrega. <\/p><p>De conformidad con lo dispuesto en la Ley 37\/1992, de 28 de diciembre, del Impuesto sobre el Valor A\u00f1adido (IVA), los pedidos de compra para su entrega y\/o prestaci\u00f3n se entender\u00e1n localizados en el territorio de aplicaci\u00f3n del IVA espa\u00f1ol si la direcci\u00f3n de entrega est\u00e1 en territorio espa\u00f1ol salvo Canarias, Ceuta y Melilla. El tipo de IVA aplicable ser\u00e1 el legalmente vigente en cada momento en funci\u00f3n del art\u00edculo concreto de que se trate. <\/p><ol start=\"7\"><li><strong><u> MEDIOS T\u00c9CNICOS PARA CORREGIR ERRORES<\/u><\/strong><\/li><\/ol><p>Se pone en conocimiento del Usuario que en caso de que detecte que se ha producido un error al introducir datos necesarios para procesar su solicitud de compra en el Sitio Web, podr\u00e1 modificar los mismos poni\u00e9ndose en contacto a trav\u00e9s de los espacios de contacto habilitados en el Sitio Web, y, en su caso, a trav\u00e9s de aquellos habilitados para contactar con el servicio de atenci\u00f3n al cliente, y\/o utilizando los datos de contacto facilitados en la cl\u00e1usula primera (Informaci\u00f3n general). Asimismo, estas informaciones tambi\u00e9n podr\u00edan subsanarse por el Usuario a trav\u00e9s de su espacio personal de conexi\u00f3n al Sitio Web. <\/p><p>En cualquier caso, el Usuario, antes de hacer clic en \u00ab\u00bb, tiene acceso al espacio, carrito, o cesta \u201c donde se van anotando sus solicitudes de compra y puede hacer modificaciones.<\/p><p>De igual forma, se remite al Usuario a consultar el Aviso Legal y Condiciones Generales de Uso y, en concreto, la Pol\u00edtica de Privacidad para recabar m\u00e1s informaci\u00f3n sobre c\u00f3mo ejercer su derecho de rectificaci\u00f3n seg\u00fan lo establecido en el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD) y en la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales.<\/p><ol start=\"8\"><li><strong><u> DEVOLUCIONES<\/u><\/strong><\/li><\/ol><p><strong>En Espa\u00f1a, no se puede devolver productos perecederos en buen estado, pero s\u00ed se pueden devolver si est\u00e1n defectuosos o en mal estado, ya sean comprados en tienda f\u00edsica o por internet. Para compras online, el derecho de desistimiento de 14 d\u00edas no se aplica a productos perecederos por riesgo de deterioro, pero s\u00ed se aplica a otros art\u00edculos, siempre que el vendedor los acepte. <\/strong><\/p><p><strong><u>Devoluci\u00f3n de productos defectuosos o error en el env\u00edo<\/u><\/strong><\/p><p>Se trata de todos aquellos casos en los que el Usuario considera que, en el momento de la entrega, el producto no se ajusta a lo estipulado en el contrato o pedido de compra, y que, por tanto, deber\u00e1 ponerse en contacto inmediatamente y hacerle saber la disconformidad existente (defecto\/error) por los mismos medios o utilizando los datos de contacto que se facilitan en el apartado anterior (Derecho de Desistimiento).<\/p><p>El Usuario ser\u00e1 entonces informado sobre c\u00f3mo proceder a la devoluci\u00f3n de los productos, y estos, una vez devueltos, ser\u00e1n examinados y se informar\u00e1 al Usuario, dentro de un plazo razonable, si procede el reembolso o, en su caso, la sustituci\u00f3n del mismo.<\/p><p>El reembolso o la sustituci\u00f3n del producto se efectuar\u00e1 lo antes posible y, en cualquier caso, dentro de los 14 d\u00edas siguientes a la fecha en la que le enviemos un correo electr\u00f3nico confirmando que procede el reembolso o la sustituci\u00f3n del art\u00edculo no conforme.<\/p><p>El importe abonado por aquellos productos que sean devueltos a causa de alg\u00fan defecto, cuando realmente exista, ser\u00e1 reembolsado \u00edntegramente, incluidos los gastos de entrega y los costes en que hubiera podido incurrir el Usuario para realizar la devoluci\u00f3n. El reembolso se efectuar\u00e1 por el mismo medio de pago que el Usuario utiliz\u00f3 para pagar la compra. <\/p><p>En todo caso, se estar\u00e1 siempre a los derechos reconocidos en la legislaci\u00f3n vigente en cada momento para el Usuario, en tanto que consumidor y usuario.<\/p><p><strong><u>Garant\u00edas<\/u><\/strong><\/p><p>El Usuario, en tanto que consumidor y usuario, goza de garant\u00edas sobre los productos que pueda adquirir a trav\u00e9s de este Sitio Web, en los t\u00e9rminos legalmente establecidos para cada tipo de producto.<\/p><p>En este sentido, se entiende que los productos son conformes con el contrato siempre que: se ajusten a la descripci\u00f3n realizada en la p\u00e1gina web en que se exponen los productos en venta y posean las cualidades presentadas en la misma; sean aptos para los usos a que ordinariamente se destinan los productos del mismo tipo; y presenten la calidad y prestaciones habituales de un producto del mismo tipo y que sean fundamentalmente esperables del mismo.<\/p><p>Cuando esto no sea as\u00ed respecto de los productos entregados al Usuario, \u00e9ste deber\u00e1 proceder tal y como se indica en el apartado Devoluci\u00f3n de productos defectuosos o error en el env\u00edo.<\/p><p>Por otra parte, podr\u00eda llegar a darse el caso que el Usuario adquiere en el Sitio Web un producto de una marca o de fabricaci\u00f3n por un tercero. En este caso, y considerando el Usuario que se trata de un producto defectuoso, \u00e9ste tambi\u00e9n tiene la posibilidad de ponerse en contacto con la marca o fabricante responsable del producto para averiguar c\u00f3mo ejercer su derecho de garant\u00eda legal directamente frente a los mismos durante los tres a\u00f1os siguientes a la entrega de dichos productos. Para ello, el Usuario debe haber conservado toda la informaci\u00f3n en relaci\u00f3n con la garant\u00eda de los productos.     <\/p><ol start=\"9\"><li><strong><u> EXONERACI\u00d3N DE RESPONSABILIDAD<\/u><\/strong><\/li><\/ol><p><u>Salvo disposici\u00f3n legal en sentido contrario, no aceptar\u00e1 ninguna responsabilidad por las siguientes p\u00e9rdidas, con independencia de su origen:<\/u><\/p><ul><li>\u2022 cualesquiera p\u00e9rdidas que no fueran atribuibles a incumplimiento alguno por su parte;<\/li><li>\u2022 p\u00e9rdidas empresariales (incluyendo lucro cesante, de ingresos, de contratos, de ahorros previstos, de datos, p\u00e9rdida del fondo de comercio o gastos innecesarios incurridos); o de<\/li><li>\u2022 toda otra p\u00e9rdida indirecta que no fuera razonablemente previsible por ambas partes en el momento en que se formaliz\u00f3 el contrato de compraventa de los productos entre ambas partes.<\/li><\/ul><p><u>Igualmente, tambi\u00e9n limita su responsabilidad en cuanto a los siguientes casos:<\/u><\/p><ul><li>\u2022 Se aplica a todas las medidas concernientes a proporcionar una visualizaci\u00f3n fiel del producto en el Sitio Web, sin embargo no se responsabiliza por las m\u00ednimas diferencias o inexactitudes que puedan existir debido a falta de resoluci\u00f3n de la pantalla, o problemas del navegador que se utilice u otros de esta \u00edndole.<\/li><li>\u2022 Actuar\u00e1 con la m\u00e1xima diligencia a efectos de poner a disposici\u00f3n de la empresa encargada del transporte del producto objeto del pedido de compra. Sin embargo, no se responsabiliza por perjuicios provenientes de un mal funcionamiento del transporte, especialmente por causas como huelgas, retenciones en carreteras, y en general cualquiera otras propias del sector, que deriven en retrasos, p\u00e9rdidas o hurtos del producto. <\/li><li>\u2022 Fallos t\u00e9cnicos que por causas fortuitas o de otra \u00edndole, impidan un normal funcionamiento del servicio a trav\u00e9s de internet. Falta de disponibilidad del Sitio Web por razones de mantenimiento u otras, que impida disponer del servicio. <\/li><li>\u2022 Pastisseria Faixat, S.L. pone todos los medios a su alcance a efectos de llevar a cabo el proceso de compra, pago y env\u00edo\/entrega de los productos, no obstante, se exime de responsabilidad por causas que no le sean imputables, caso fortuito o fuerza mayor.<\/li><li>\u2022 No se har\u00e1 responsable del mal uso y\/o del desgaste de los productos que hayan sido utilizados por el Usuario.<\/li><\/ul><p> Al mismo tiempo, tampoco se har\u00e1 responsable de una devoluci\u00f3n err\u00f3nea realizada por el Usuario. Es responsabilidad del Usuario devolver el producto correcto. <\/p><ul><li>En general, no se responsabilizar\u00e1 por ning\u00fan incumplimiento o retraso en el cumplimiento de alguna de las obligaciones asumidas, cuando el mismo se deba a acontecimientos que est\u00e1n fuera de su control razonable, es decir, que se deban a causa de fuerza mayor, y \u00e9sta podr\u00e1 incluir, a modo enunciativo, pero no exhaustivo:<\/li><\/ul><p>o Huelgas, cierres patronales u otras medidas reivindicativas<\/p><p>o Conmoci\u00f3n civil, revuelta, invasi\u00f3n, amenaza o ataque terrorista, guerra (declarada o no) o amenaza o preparativos de guerra.<\/p><p>o Incendio, explosi\u00f3n, tormenta, inundaci\u00f3n, terremoto, hundimiento, epidemia o cualquier otro desastre natural.<\/p><p>o Imposibilidad de uso de trenes, barcos, aviones, transportes de motor u otros medios de transporte, p\u00fablicos o privados.<\/p><p>o Imposibilidad de utilizar sistemas p\u00fablicos o privados de telecomunicaciones<\/p><p>o Actos, decretos, legislaci\u00f3n, normativa o restricciones de cualquier gobierno o autoridad.<\/p><p>De esta forma, las obligaciones quedar\u00e1n suspendidas durante el periodo en que la causa de fuerza mayor contin\u00fae, y dispondr\u00e1 de una ampliaci\u00f3n en el plazo para cumplirlas por un periodo de tiempo igual al que dure la causa de fuerza mayor. pondr\u00e1 todos los medios razonables para encontrar una soluci\u00f3n que le permita cumplir con sus obligaciones a pesar de la causa de fuerza mayor. <\/p><ol start=\"10\"><li><strong><u> COMUNICACIONES POR ESCRITO Y NOTIFICACIONES<\/u><\/strong><\/li><\/ol><p>Mediante el uso de este Sitio Web, el Usuario acepta que la mayor parte de las comunicaciones sean electr\u00f3nicas (correo electr\u00f3nico o avisos publicados en el Sitio Web).<\/p><p>A efectos contractuales, el Usuario consiente en usar este medio electr\u00f3nico de comunicaci\u00f3n y reconoce que todo contrato, notificaci\u00f3n, informaci\u00f3n y dem\u00e1s comunicaciones que se le env\u00eden de forma electr\u00f3nica y que cumplen con los requisitos legales de ser por escrito. Esta condici\u00f3n no afectar\u00e1 a los derechos reconocidos por ley al Usuario. <\/p><p>El Usuario puede enviar notificaciones y\/o comunicarse a trav\u00e9s de los datos de contacto que en estas Condiciones se facilitan y, en su caso, a trav\u00e9s de los espacios de contacto del Sitio Web.<\/p><p>Igualmente, salvo que se estipule lo contrario, puede contactar y\/o notificar al Usuario en su correo electr\u00f3nico o en la direcci\u00f3n postal facilitada.<\/p><ol start=\"11\"><li><strong><u> RENUNCIA<\/u><\/strong><\/li><\/ol><p>Ninguna renuncia de Pastisseria Faixat,S.L. a un derecho o acci\u00f3n legal concreta o la falta de requerimiento por cumplimiento estricto por el Usuario de alguna de sus obligaciones supondr\u00e1, ni una renuncia a otros derechos o acciones derivados de un contrato o de las Condiciones, ni exonerar\u00e1 al Usuario del cumplimiento de sus obligaciones.<\/p><p>Ninguna renuncia de Pastisseria Faixat, S.L. a alguna de las presentes Condiciones o a los derechos o acciones derivados de un contrato surtir\u00e1 efecto, a no ser que se establezca expresamente que es una renuncia y se formalice y se le comunique al Usuario por escrito.<\/p><ol start=\"12\"><li><strong><u> NULIDAD<\/u><\/strong><\/li><\/ol><p>Si alguna de las presentes Condiciones fuera declaradas nulas y sin efecto por resoluci\u00f3n firme dictada por autoridad competente, el resto de las cl\u00e1usulas permanecer\u00e1n en vigor, sin que queden afectadas por dicha declaraci\u00f3n de nulidad.<\/p><ol start=\"13\"><li><strong><u> ACUERDO COMPLETO<\/u><\/strong><\/li><\/ol><p>Las presentes Condiciones y todo documento al que se haga referencia expresa en estas constituyen el acuerdo \u00edntegro existente entre el Usuario y Pastisseria Faixat, S.L. en relaci\u00f3n con el objeto de compraventa y sustituyen a cualquier otro pacto, acuerdo o promesa anterior convenida verbalmente o por escrito por las mismas partes.<\/p><p>El Usuario reconoce haber consentido la celebraci\u00f3n de un contrato sin haber confiado en ninguna declaraci\u00f3n o promesa hecha por la otra parte, salvo aquello que figura expresamente mencionado en las presentes Condiciones.<\/p><p> <\/p><ol start=\"14\"><li><strong><u> PROTECCI\u00d3N DE DATOS<\/u><\/strong><\/li><\/ol><p>La informaci\u00f3n o datos de car\u00e1cter personal que el Usuario facilite en el curso de una transacci\u00f3n en el Sitio Web, ser\u00e1n tratados con arreglo a lo establecido en la Pol\u00edtica de Privacidad o de protecci\u00f3n de datos (contenida, en su caso, en el Aviso Legal y Condiciones Generales de Uso). Al acceder, navegar y\/o usar el Sitio Web el Usuario consiente el tratamiento de dicha informaci\u00f3n y datos y declara que toda la informaci\u00f3n o datos que facilita son veraces. <\/p><ol start=\"15\"><li><strong><u> LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/u><\/strong><\/li><\/ol><p>El acceso, navegaci\u00f3n y\/o uso de este Sitio Web y los contratos de compra de productos a trav\u00e9s del mismo se regir\u00e1n por la legislaci\u00f3n espa\u00f1ola.<\/p><p>Cualquier controversia, problema o desacuerdo que surja o est\u00e9 relacionado con el acceso, navegaci\u00f3n y\/o uso del Sitio Web, o con la interpretaci\u00f3n y ejecuci\u00f3n de estas Condiciones, o con los contratos de venta entre y el Usuario, ser\u00e1 sometida a la jurisdicci\u00f3n no exclusiva de los juzgados y tribunales espa\u00f1oles.<\/p><ol start=\"16\"><li><strong><u> QUEJAS Y RECLAMACIONES<\/u><\/strong><\/li><\/ol><p>El Usuario puede hacer llegar sus quejas, reclamaciones o todo otro comentario que desee realizar a trav\u00e9s de los datos de contacto que se facilitan al principio de estas Condiciones (Informaci\u00f3n General).<\/p><p>Adem\u00e1s, dispone de hojas oficiales de reclamaci\u00f3n a disposici\u00f3n de los consumidores y usuarios, y que estos pueden solicitar a en cualquier momento, utilizando los datos de contacto que se facilitan al principio de estas Condiciones (Informaci\u00f3n General).<\/p><p>Asimismo, si de la celebraci\u00f3n de este contrato de compra entre y el Usuario emanara una controversia, el Usuario como consumidor puede solicitar una soluci\u00f3n extrajudicial de controversias, de acuerdo con el Reglamento (UE) 524\/2013 del Parlamento Europeo y del Consejo, de 21 de mayo de 2013, sobre resoluci\u00f3n de litigios en l\u00ednea en materia de consumo y por el que se modifica el Reglamento (CE) 2006\/2004 y la Directiva 2009\/22\/CE. Puede acceder a este m\u00e9todo a trav\u00e9s del siguiente sitio web: https:\/\/ec.europa.eu\/consumers\/odr\/.<\/p><p><strong><u>Este documento de Condiciones Generales de Venta tiene vigencia desde su incorporaci\u00f3n a la p\u00e1gina web de venta electr\u00f3nica de PASTISSERIA FAIXAT,S.L. cuyos datos constan en la primera p\u00e1gina de este documento.<\/u><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>INFORMACI\u00d3N GENERAL La titularitat d&#8217;aquest lloc web, (d&#8217;ara endavant Lloc Web) l&#8217;ostenta: Pastisseria Faixat S.L., tiene su domicilio social en calle Muntaner, 159-161, local, c\u00f3digo postal 08036 \u2013 Barcelona. Se halla inscrita en el Registro Mercantil de Barcelona al Tomo 9409, Folio 154, hoja 80743,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-644","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/pages\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":4,"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/pages\/644\/revisions"}],"predecessor-version":[{"id":1999,"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/pages\/644\/revisions\/1999"}],"wp:attachment":[{"href":"https:\/\/pastisseriafaixat.com\/es\/wp-json\/wp\/v2\/media?parent=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}